{"id":89,"count":1,"description":"","link":"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/","name":"chinainvitationletter","slug":"chinainvitationletter","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>chinainvitationletter Archives - Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"chinainvitationletter Archives - Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ChinaVisaDept\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/\",\"url\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/\",\"name\":\"chinainvitationletter Archives - Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"chinainvitationletter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/#website\",\"url\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/\",\"name\":\"Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/#organization\",\"name\":\"China Visa Department\",\"url\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-content\/uploads\/2017\/05\/cropped-China-Work_02.png\",\"contentUrl\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-content\/uploads\/2017\/05\/cropped-China-Work_02.png\",\"width\":432,\"height\":30,\"caption\":\"China Visa Department\"},\"image\":{\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ChinaVisaDepartment\/\",\"https:\/\/x.com\/ChinaVisaDept\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"chinainvitationletter Archives - Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/","og_locale":"en_US","og_type":"article","og_title":"chinainvitationletter Archives - Blog","og_url":"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/","og_site_name":"Blog","twitter_card":"summary_large_image","twitter_site":"@ChinaVisaDept","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/","url":"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/","name":"chinainvitationletter Archives - Blog","isPartOf":{"@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/#website"},"breadcrumb":{"@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/tag\/chinainvitationletter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.chinavisadepartment.com\/news-updates\/"},{"@type":"ListItem","position":2,"name":"chinainvitationletter"}]},{"@type":"WebSite","@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/#website","url":"https:\/\/www.chinavisadepartment.com\/news-updates\/","name":"Blog","description":"","publisher":{"@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.chinavisadepartment.com\/news-updates\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/#organization","name":"China Visa Department","url":"https:\/\/www.chinavisadepartment.com\/news-updates\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/#\/schema\/logo\/image\/","url":"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-content\/uploads\/2017\/05\/cropped-China-Work_02.png","contentUrl":"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-content\/uploads\/2017\/05\/cropped-China-Work_02.png","width":432,"height":30,"caption":"China Visa Department"},"image":{"@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ChinaVisaDepartment\/","https:\/\/x.com\/ChinaVisaDept"]}]}},"_links":{"self":[{"href":"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-json\/wp\/v2\/tags\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-json\/wp\/v2\/posts?tags=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}