{"id":1,"count":32,"description":"Browse general articles, updates, and helpful info related to China travel, visas, and news. A mix of insights for China travelers.","link":"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/","name":"General","slug":"general","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>General Archives - Blog<\/title>\n<meta name=\"description\" content=\"Browse general articles, updates, and helpful info related to China travel, visas, and news. A mix of insights for China travelers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"General Archives - Blog\" \/>\n<meta property=\"og:description\" content=\"Browse general articles, updates, and helpful info related to China travel, visas, and news. A mix of insights for China travelers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ChinaVisaDept\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/\",\"url\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/\",\"name\":\"General Archives - Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/#website\"},\"description\":\"Browse general articles, updates, and helpful info related to China travel, visas, and news. A mix of insights for China travelers.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"General\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/#website\",\"url\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/\",\"name\":\"Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/#organization\",\"name\":\"China Visa Department\",\"url\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-content\/uploads\/2017\/05\/cropped-China-Work_02.png\",\"contentUrl\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-content\/uploads\/2017\/05\/cropped-China-Work_02.png\",\"width\":432,\"height\":30,\"caption\":\"China Visa Department\"},\"image\":{\"@id\":\"https:\/\/www.chinavisadepartment.com\/news-updates\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ChinaVisaDepartment\/\",\"https:\/\/x.com\/ChinaVisaDept\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"General Archives - Blog","description":"Browse general articles, updates, and helpful info related to China travel, visas, and news. A mix of insights for China travelers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/","og_locale":"en_US","og_type":"article","og_title":"General Archives - Blog","og_description":"Browse general articles, updates, and helpful info related to China travel, visas, and news. A mix of insights for China travelers.","og_url":"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/","og_site_name":"Blog","twitter_card":"summary_large_image","twitter_site":"@ChinaVisaDept","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/","url":"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/","name":"General Archives - Blog","isPartOf":{"@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/#website"},"description":"Browse general articles, updates, and helpful info related to China travel, visas, and news. A mix of insights for China travelers.","breadcrumb":{"@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/category\/general\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.chinavisadepartment.com\/news-updates\/"},{"@type":"ListItem","position":2,"name":"General"}]},{"@type":"WebSite","@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/#website","url":"https:\/\/www.chinavisadepartment.com\/news-updates\/","name":"Blog","description":"","publisher":{"@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.chinavisadepartment.com\/news-updates\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/#organization","name":"China Visa Department","url":"https:\/\/www.chinavisadepartment.com\/news-updates\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/#\/schema\/logo\/image\/","url":"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-content\/uploads\/2017\/05\/cropped-China-Work_02.png","contentUrl":"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-content\/uploads\/2017\/05\/cropped-China-Work_02.png","width":432,"height":30,"caption":"China Visa Department"},"image":{"@id":"https:\/\/www.chinavisadepartment.com\/news-updates\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ChinaVisaDepartment\/","https:\/\/x.com\/ChinaVisaDept"]}]}},"_links":{"self":[{"href":"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.chinavisadepartment.com\/news-updates\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}